{"id":437,"date":"2010-10-14T15:53:25","date_gmt":"2010-10-14T13:53:25","guid":{"rendered":"http:\/\/liceoausiliatrice.it\/liceo\/"},"modified":"2022-12-04T00:51:24","modified_gmt":"2022-12-03T23:51:24","slug":"il-liceo-delle-scienze-umane","status":"publish","type":"page","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/il-liceo-delle-scienze-umane\/","title":{"rendered":"Liceo delle Scienze Umane"},"content":{"rendered":"<div id=\"attachment_1067\" style=\"width: 829px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/mauxsocialclub.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-1067\" class=\" wp-image-1067\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/mauxsocialclub.jpg\" alt=\"mauxsocialclub\" width=\"819\" height=\"470\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/mauxsocialclub.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/mauxsocialclub-300x172.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/mauxsocialclub-700x401.jpg 700w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/a><p id=\"caption-attachment-1067\" class=\"wp-caption-text\">I ragazzi del Liceo delle Scienze Umane &#8211; sezione Internazionale, impegnati in un&#8217;attivit\u00e0 con i bimbi della scuola dell&#8217;Infanzia<\/p><\/div>\n<p>Il Liceo delle Scienze Umane si propone di fornire agli studenti importanti strumenti per orientarsi:<\/p>\n<ul>\n<li>Nella dimensione interiore della mente e delle emozioni<\/li>\n<li>Nella dimensione esterna delle relazioni sociali ed economiche<\/li>\n<\/ul>\n<p>Il liceo si articola in due indirizzi:<\/p>\n<ul>\n<li><strong>LICEO DELLE SCIENZE UMANE<\/strong><\/li>\n<li><strong>OPZIONE ECONOMICO-SOCIALE<\/strong> (ormai diventato LES Liceo economico sociale <a title=\"LES \u2013 Liceo Economico Sociale\" href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/les-liceo-economico-sociale\/\">vedi sezione apposita<\/a>)<\/li>\n<\/ul>\n<p>Il <em>percorso internazionale<\/em> fornisce agli studenti ore aggiuntive con insegnante madrelingua per il miglioramento della lingua straniera.<\/p>\n<h2>IL LICEO DELLE SCIENZE UMANE<br \/>\n<span style=\"color: #888888;\">con percorso internazionale<\/span><\/h2>\n<p>Approfondisce la conoscenza della mente e della persona, concentrandosi in particolare sulla Psicologia e sulle Scienze dell&#8217;Educazione, rafforzando inoltre lo studio delle scienze naturali e della cultura classica, attraverso la filosofia e il latino.<\/p>\n<p>Gli studenti, a conclusione del percorso di studio, devono essere in grado di<\/p>\n<ul>\n<li>conoscere i principali campi di indagine delle scienze umane e collegare, interdisciplinarmente, le competenze specifiche della ricerca pedagogica, psicologica e socio-antropologica;<\/li>\n<li>definire con criteri scientifici, in situazioni reali o simulate, le variabili che influenzano i fenomeni educativi e i processi formativi;<\/li>\n<li>confrontare teorie e strumenti necessari per comprendere nella realt\u00e0 attuale la complessit\u00e0 della condizione e della convivenza umana, con particolare attenzione ai luoghi dell\u2019educazione, ai servizi alla persona, al mondo del lavoro, ai processi interculturali e alle istanze espresse dalla necessit\u00e0 di \u201capprendere per tutta la vita\u201d; familiarizzare con le principali metodologie relazionali e comunicative comprese quelle relative alla\u00a0<em>media education<\/em>.<\/li>\n<\/ul>\n<h3><\/h3>\n<h3>PIANO DI STUDI<\/h3>\n<table>\n<tbody>\n<tr>\n<th rowspan=\"3\" scope=\"row\" width=\"380\">Attivit\u00e0 e insegnamenti obbligatori per tutti gli studenti<\/th>\n<th colspan=\"2\" scope=\"row\" width=\"113\">1\u00b0 BIENNIO<\/th>\n<th colspan=\"2\" scope=\"row\" width=\"113\">2\u00b0 BIENNIO<\/th>\n<th rowspan=\"2\" scope=\"row\" width=\"81\">5\u00b0<br \/>\nANNO<\/th>\n<\/tr>\n<tr>\n<th scope=\"row\" width=\"56\">1\u00b0<br \/>\nANNO<\/th>\n<th scope=\"row\" width=\"56\">2\u00b0<br \/>\nANNO<\/th>\n<th scope=\"row\" width=\"56\">3\u00b0<br \/>\nANNO<\/th>\n<th scope=\"row\" width=\"56\">4\u00b0<br \/>\nANNO<\/th>\n<\/tr>\n<tr>\n<th colspan=\"5\" width=\"306\">Orario settimanale<\/th>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Lingua e letteratura italiana<\/th>\n<td class=\"spec\" scope=\"col\" width=\"56\">4<\/td>\n<td class=\"spec\" scope=\"col\" width=\"56\">4<\/td>\n<td class=\"spec\" scope=\"col\" width=\"56\">4<\/td>\n<td class=\"spec\" scope=\"col\" width=\"56\">4<\/td>\n<td class=\"spec\" scope=\"col\" width=\"81\">4<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Lingua latina<\/th>\n<td class=\"alt\" scope=\"col\" width=\"56\">3<\/td>\n<td class=\"alt\" scope=\"col\" width=\"56\">3<\/td>\n<td class=\"alt\" scope=\"col\" width=\"56\">2<\/td>\n<td class=\"alt\" scope=\"col\" width=\"56\">2<\/td>\n<td class=\"alt\" scope=\"col\" width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">LS Inglese<\/th>\n<td scope=\"col\" width=\"56\">3<\/td>\n<td scope=\"col\" width=\"56\">3<\/td>\n<td scope=\"col\" width=\"56\">3<\/td>\n<td scope=\"col\" width=\"56\">3<\/td>\n<td scope=\"col\" width=\"81\">3<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" width=\"380\">Lettorato Inglese (insegnante madrelingua)<\/th>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"81\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Storia e Geografia<\/th>\n<td width=\"56\">2+1<\/td>\n<td width=\"56\">2+1<\/td>\n<td width=\"56\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"81\"><\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Storia<\/th>\n<td class=\"alt\" width=\"56\"><\/td>\n<td class=\"alt\" width=\"56\"><\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Filosofia<\/th>\n<td width=\"56\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"56\">3<\/td>\n<td width=\"56\">3<\/td>\n<td width=\"81\">3<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Scienze umane*<\/th>\n<td class=\"alt\" width=\"56\">4<\/td>\n<td class=\"alt\" width=\"56\">4<\/td>\n<td class=\"alt\" width=\"56\">5<\/td>\n<td class=\"alt\" width=\"56\">5<\/td>\n<td class=\"alt\" width=\"81\">5<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Diritto ed economia<\/th>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"56\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"81\"><\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Matematica<\/th>\n<td class=\"alt\" width=\"56\">3<\/td>\n<td class=\"alt\" width=\"56\">3<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Fisica<\/th>\n<td width=\"56\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Scienze naturali**<\/th>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Storia dell\u2019arte<\/th>\n<td width=\"56\"><\/td>\n<td width=\"56\"><\/td>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">Scienze motorie e sportive<\/th>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"56\">2<\/td>\n<td class=\"alt\" width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"spec\" scope=\"col\" width=\"380\">Religione cattolica e coordinamento<\/th>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"56\">2<\/td>\n<td width=\"81\">2<\/td>\n<\/tr>\n<tr>\n<th class=\"specalt\" scope=\"col\" width=\"380\">L@arn.it!<\/th>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"56\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<td class=\"alt\" width=\"81\"><span style=\"color: #ff0000;\">1<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: left;\">*Antropologia, Pedagogia, Psicologia e Sociologia<br \/>\n**Biologia, Chimica, Scienze della Terra<\/p>\n<p><span style=\"font-family: Oswald, sans-serif; font-size: 32px; letter-spacing: 1px; line-height: 1.62em;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Liceo delle Scienze Umane si propone di fornire agli studenti importanti strumenti per orientarsi: Nella dimensione interiore della mente e delle emozioni Nella dimensione esterna delle relazioni sociali ed economiche Il liceo si articola in due indirizzi: LICEO DELLE SCIENZE UMANE OPZIONE ECONOMICO-SOCIALE (ormai diventato LES Liceo economico sociale vedi sezione apposita) Il percorso [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","vkExUnit_sitemap":"","_veu_custom_css":"","veu_display_promotion_alert":"","_exclude_from_list_pages":"","vkexunit_cta_each_option":"","vkExUnit_childPageIndex":"","vkExUnit_pageList_ancestor":"","vkExUnit_contact_enable":"","_lightning_design_setting":[],"footnotes":""},"class_list":["post-437","page","type-page","status-publish","hentry"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/pages\/437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=437"}],"version-history":[{"count":24,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/pages\/437\/revisions"}],"predecessor-version":[{"id":2039,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/pages\/437\/revisions\/2039"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}