{"id":1079,"date":"2013-11-17T23:09:17","date_gmt":"2013-11-17T22:09:17","guid":{"rendered":"http:\/\/www.istitutomariausiliatrice.it\/liceo\/?p=1079"},"modified":"2013-11-17T23:13:59","modified_gmt":"2013-11-17T22:13:59","slug":"1079","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2013\/11\/17\/1079\/","title":{"rendered":"La Quarta A Scienze Umane: The wheels on the bus"},"content":{"rendered":"<p><iframe src=\"\/\/www.youtube.com\/embed\/9QSRnhv4EBE\" width=\"300\" allowfullscreen=\"\" frameborder=\"0\"><\/iframe><\/p>\n<p>Siamo i ragazzi della 4\u00b0A del liceo delle scienze umane, che in collaborazione con la scuola materna abbiamo realizzato questo video, cercando di coinvolgere i bambini nell&#8217;apprendimento della lingua inglese (gi\u00e0 dalla scuola materna nel nostro istituto abbiamo una sezione internazionale, che arriva ad avere anche 8 ore di inglese\u00a0 asettimana) tramite l&#8217;ascolto e la ripetizione di gesti e suoni.<\/p>\n<p>Lorenzo Tabasso<\/p>\n<p>\u00ec\u00ec<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo i ragazzi della 4\u00b0A del liceo delle scienze umane, che in collaborazione con la scuola materna abbiamo realizzato questo video, cercando di coinvolgere i bambini nell&#8217;apprendimento della lingua inglese (gi\u00e0 dalla scuola materna nel nostro istituto abbiamo una sezione internazionale, che arriva ad avere anche 8 ore di inglese\u00a0 asettimana) tramite l&#8217;ascolto e la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"","vkexunit_cta_each_option":"","_lightning_design_setting":[],"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1079","post","type-post","status-publish","format-video","hentry","category-liceo-delle-scienze-umane","post_format-post-format-video"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=1079"}],"version-history":[{"count":5,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1079\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1079\/revisions\/1084"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=1079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=1079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=1079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}