{"id":1226,"date":"2014-04-08T10:16:02","date_gmt":"2014-04-08T08:16:02","guid":{"rendered":"http:\/\/www.istitutomariausiliatrice.it\/liceo\/?p=1226"},"modified":"2014-04-08T10:29:19","modified_gmt":"2014-04-08T08:29:19","slug":"settimana-della-bioetica","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2014\/04\/08\/settimana-della-bioetica\/","title":{"rendered":"SETTIMANA DELLA BIOETICA"},"content":{"rendered":"<p><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.27.52.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1227\" alt=\"Screenshot 2014-04-08 09.27.52\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.27.52.png\" width=\"808\" height=\"484\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.27.52.png 808w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.27.52-300x179.png 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.27.52-700x419.png 700w\" sizes=\"auto, (max-width: 808px) 100vw, 808px\" \/><\/a><\/p>\n<p>In occasione della settimana della bioetica, ho partecipato al giorno inaugurale del 24 Marzo con un intervento su etica e web, insieme al prof. Beatrice, la dott.ssa Massaro e il giornalista del &#8220;La Stampa&#8221;, Marco Accossato.<a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.26.58.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1228\" alt=\"Screenshot 2014-04-08 09.26.58\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.26.58.png\" width=\"787\" height=\"164\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.26.58.png 787w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.26.58-300x62.png 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-09.26.58-700x145.png 700w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><\/a><br \/>\nDa questo<a href=\"https:\/\/www.dropbox.com\/s\/tkwg1vo4of7fn5q\/bievol_etica_web.pdf\"> link<\/a>, \u00e8 possibile scaricare la presentazione. Per approfondimenti ho creato la pagina twitter gi\u00e0 per il corso agli ambasciatori di salute <a href=\"http:\/\/twitter.com\/flwBianConiglio \">@flwBianConiglio<\/a><\/p>\n<p><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.34.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1233\" alt=\"Screenshot 2014-04-08 10.21.34\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.34.png\" width=\"812\" height=\"121\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.34.png 812w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.34-300x44.png 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.34-700x104.png 700w\" sizes=\"auto, (max-width: 812px) 100vw, 812px\" \/><\/a>I nostri &#8220;Ambasciatori di Salute&#8221; insieme al prof. Damasco, hanno esplicato il loro lavoro all&#8217;Avogadro gioved\u00ec 27 marzo. A breve saranno pubblicati gli interventi.<a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.49.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1232\" alt=\"Screenshot 2014-04-08 10.21.49\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.49.png\" width=\"810\" height=\"91\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.49.png 810w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.49-300x33.png 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Screenshot-2014-04-08-10.21.49-700x78.png 700w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><br \/>\n<\/a><\/p>\n<p>Venerd\u00ec 28 Marzo, il prof. Bruno Alessandro, ha tenuto una lezione sulla prevenzione al diabete.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>il preside Filippo Buzio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della settimana della bioetica, ho partecipato al giorno inaugurale del 24 Marzo con un intervento su etica e web, insieme al prof. Beatrice, la dott.ssa Massaro e il giornalista del &#8220;La Stampa&#8221;, Marco Accossato. Da questo link, \u00e8 possibile scaricare la presentazione. Per approfondimenti ho creato la pagina twitter gi\u00e0 per il corso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"","vkexunit_cta_each_option":"","_lightning_design_setting":[],"footnotes":""},"categories":[56,25,10,11,12,1],"tags":[58,57],"class_list":["post-1226","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-ambasciatori-di-salute","category-les-liceo-economico-sociale","category-liceo-della-comunicazione","category-liceo-delle-scienze-umane","category-liceo-linguistico","category-senza-categoria","tag-bievol","tag-bioetica","post_format-post-format-image"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=1226"}],"version-history":[{"count":5,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1226\/revisions"}],"predecessor-version":[{"id":1235,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/1226\/revisions\/1235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media\/1227"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=1226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=1226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=1226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}