{"id":396,"date":"2010-06-01T13:18:59","date_gmt":"2010-06-01T11:18:59","guid":{"rendered":"http:\/\/liceoausiliatrice.it\/liceo\/?p=396"},"modified":"2010-06-01T13:18:59","modified_gmt":"2010-06-01T11:18:59","slug":"consegna-documentazione-di-fine-anno","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2010\/06\/01\/consegna-documentazione-di-fine-anno\/","title":{"rendered":"Consegna documentazione di fine anno"},"content":{"rendered":"<p><a href=\"http:\/\/liceoausiliatrice.it\/liceo\/files\/Immagine-021.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-399\" src=\"http:\/\/liceoausiliatrice.it\/liceo\/files\/Immagine-021-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>In data odierna \u00e8 stata consegnata agli studenti la circolare di fine anno e in allegato la domanda di iscrizione, il prospetto della retta scolastica e il prospetto dei criteri di promozione, di sospensione del giudizio e di non promozione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In data odierna \u00e8 stata consegnata agli studenti la circolare di fine anno e in allegato la domanda di iscrizione, il prospetto della retta scolastica e il prospetto dei criteri di promozione, di sospensione del giudizio e di non promozione.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"","vkexunit_cta_each_option":"","_lightning_design_setting":[],"footnotes":""},"categories":[5,6],"tags":[],"class_list":["post-396","post","type-post","status-publish","format-standard","hentry","category-featured","category-headline"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=396"}],"version-history":[{"count":0,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/396\/revisions"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}