{"id":4411,"date":"2025-10-21T09:23:46","date_gmt":"2025-10-21T07:23:46","guid":{"rendered":"https:\/\/istitutomariausiliatrice.it\/liceo\/?p=4411"},"modified":"2025-11-19T16:43:15","modified_gmt":"2025-11-19T15:43:15","slug":"4411","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2025\/10\/21\/4411\/","title":{"rendered":"Un viaggio non \u00e8 solo un luogo, ma le persone che incontriamo.  La nostra esperienza con gli studenti austriaci."},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La nostra scuola ha avuto il privilegio di accogliere otto studenti austriaci, coprotagonisti di un progetto che ha unito culture diverse attraverso il linguaggio del teatro. La nostra insegnante di tedesco prof.ssa Boscolo ha conosciuto la corrispondete grazie al job shadowing in Austria legato alla nostra partecipazione al consorzio USR PIEMONTE. Dopo mesi di collaborazione a distanza, l\u2019incontro in presenza si \u00e8 trasformato in un\u2019esperienza indimenticabile, a seguito della presentazione del nostro video al prestigioso Teatro Regio.<\/span><\/p>\n<p><strong>Il primo giorno: accoglienza e prime scoperte\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">Il 22 settembre abbiamo accolto i nostri ospiti alla caffetteria di Valdocco, dove la colazione condivisa ha dato il via a tre giornate di amicizia e curiosit\u00e0 reciproca. A scuola, nella sala rossa, il preside ha rivolto agli studenti un caloroso benvenuto, consegnando loro un piccolo omaggio: una borraccia e una sacca con il logo dell\u2019istituto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dopo la foto di gruppo con il cartellone realizzato dagli studenti di 4B, \u00e8 seguito un breve tour dell\u2019edificio. Nel corso della mattinata, i ragazzi austriaci hanno partecipato a diverse lezioni \u2014 di tedesco, francese ed educazione motoria \u2014 per immergersi nella vita scolastica italiana.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il pomeriggio \u00e8 stato dedicato alla scoperta del centro di Torino, sotto la nostra guida esperta: da piazza Statuto a piazza Vittorio, passando per via Garibaldi, piazza Castello e via Po. La giornata si \u00e8 conclusa con un aperitivo conviviale, occasione perfetta per conoscerci meglio.<\/span><\/p>\n<p><strong>Il secondo giorno: scuola, cultura e divertimento\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">La mattina \u00e8 proseguita con la partecipazione alle lezioni insieme a noi, mentre il pomeriggio \u00e8 stato riservato alla visita della citt\u00e0. La sera ci siamo ritrovati tutti insieme per una pizza da Sorbillo e una piacevole passeggiata nel centro illuminato, tra chiacchiere e risate.<\/span><\/p>\n<p><strong>Il terzo giorno: saluti e nuovi legami\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019ultima giornata \u00e8 stata dedicata alle attivit\u00e0 in classe e alla preparazione della serata conclusiva. Dopo un aperitivo informale, abbiamo cenato tutti insieme \u2014 studenti e insegnanti \u2014 in un ristorante tipico piemontese. \u00c8 stato un momento speciale, ricco di dialogo, scambi culturali (e culinari) e tanta allegria.<\/span><\/p>\n<p>\u00a0<\/p>\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"533\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG_1257.jpg\" alt=\"\" class=\"wp-image-4456 size-full\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG_1257.jpg 400w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG_1257-225x300.jpg 225w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Un\u2019esperienza che lascia il segno.&nbsp;<\/strong><\/p>\n\n\n\n<p>Questo progetto non \u00e8 stato solo un\u2019occasione per migliorare la lingua, ma soprattutto un\u2019esperienza di crescita personale e culturale. Le giornate trascorse con gli studenti austriaci hanno creato legami autentici e duraturi, dimostrando quanto l\u2019incontro tra culture possa arricchire, unire e ispirare.<\/p>\n\n\n\n<p>Che dire di pi\u00f9?! Ci vediamo presto,&nbsp; in Austria!<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nostra scuola ha avuto il privilegio di accogliere otto studenti austriaci, coprotagonisti di un progetto che ha unito culture diverse attraverso il linguaggio del teatro. La nostra insegnante di tedesco prof.ssa Boscolo ha conosciuto la corrispondete grazie al job shadowing in Austria legato alla nostra partecipazione al consorzio USR PIEMONTE. Dopo mesi di collaborazione [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4379,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"common","vkexunit_cta_each_option":"","_lightning_design_setting":{"layout":"default"},"footnotes":""},"categories":[105,12,78],"tags":[],"class_list":["post-4411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-s-2025-26","category-liceo-linguistico","category-we-are-maux"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=4411"}],"version-history":[{"count":6,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4411\/revisions"}],"predecessor-version":[{"id":4457,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4411\/revisions\/4457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media\/4379"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=4411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=4411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=4411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}