{"id":4663,"date":"2026-05-07T12:22:51","date_gmt":"2026-05-07T10:22:51","guid":{"rendered":"https:\/\/istitutomariausiliatrice.it\/liceo\/?p=4663"},"modified":"2026-05-08T11:36:52","modified_gmt":"2026-05-08T09:36:52","slug":"alle-radici-per-costruire-il-futuro","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2026\/05\/07\/alle-radici-per-costruire-il-futuro\/","title":{"rendered":"\u00a0ALLE RADICI PER COSTRUIRE IL FUTURO\u00a0"},"content":{"rendered":"\n<p><em>16- 17 aprile 2026,&nbsp;<\/em><\/p>\n\n\n\n<p><em>Torino&nbsp;<\/em><\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>INTRODUZIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>Il 16 e il 17 aprile si sono riuniti a Torino i rappresentanti d\u2019istituto delle scuole salesiane di tutta Italia.&nbsp;<\/p>\n\n\n\n<p>Il primo incontro \u00e8 avvenuto il 4 marzo, insieme agli studenti di tutte le scuole coinvolte.&nbsp;<\/p>\n\n\n\n<p>La ricorrenza di quel giorno era dedicata ai 150 anni di viaggio di Don Bosco in cui ogni rappresentante attraverso delle domande portava alla riflessione gli alunni e il centro di quest\u2019attivit\u00e0 era una carta d\u2019imbarco che poi in un secondo momento andava compilata. Ci si domandava dunque quale fosse la destinazione del proprio viaggio personale, se valesse la pena arrivarci, con chi si volesse andare e molto altro.&nbsp;<\/p>\n\n\n\n<p>Quel giorno, anche se attraverso uno schermo, ci siamo visti per la prima volta.&nbsp;<\/p>\n\n\n\n<p>Le settimane successive sono state dedicate all\u2019organizzazione dell\u2019incontro che ci sarebbe stato ad aprile. Abbiamo pensato, insieme ai rappresentanti della Mazzarello di Torino, alle attivit\u00e0 da svolgere insieme a tutti loro, improntate inizialmente ad una conoscenza reciproca per poi incentrarsi sugli aspetti fondamentali della vita dell\u2019uomo: l\u2019amicizia, la spiritualit\u00e0, la reciprocit\u00e0, il gioco e la condivisione.&nbsp;<\/p>\n\n\n\n<p>Questo tempo speso \u00e8 stato essenziale per arrivare preparati ai giorni pieni di emozioni che abbiamo vissuto.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"4676\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1-1024x768.jpg\" alt=\"\" class=\"wp-image-4676\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1-1024x768.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1-300x225.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1-768x576.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1-1536x1152.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0016-1.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Risorsa-1-100-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"330\" data-id=\"4677\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Risorsa-1-100-1.jpg\" alt=\"\" class=\"wp-image-4677\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Risorsa-1-100-1.jpg 467w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Risorsa-1-100-1-300x212.jpg 300w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p><strong>16 aprile&nbsp;<\/strong><\/p>\n\n\n\n<p>Questa esperienza la possiamo considerare un percorso, un viaggio.&nbsp;<\/p>\n\n\n\n<p>Dopo la lunga organizzazione iniziale, che possiamo considerare un po\u2019 come la preparazione delle valigie, il 16 aprile \u00e8 iniziato il vero e proprio viaggio.&nbsp;<\/p>\n\n\n\n<p>La mattina abbiamo preparato una colazione sul terrazzo che attendeva i nostri compagni, le attivit\u00e0 pratiche per poter riempire il tempo in modo produttivo e un piccolo \u201ckit\u201d da dare ad ognuno di loro che conteneva dei gadget della nostra scuola per far provare a loro ci\u00f2 che noi sentiamo al Maux, aria di casa.&nbsp;<\/p>\n\n\n\n<p>Con il tempo sono arrivati tutti, hanno lasciato le valige in hotel, hanno mangiato e prima di pranzo ci siamo riuniti nella Sala Rossa della nostra scuola, luogo in cui \u00e8 avvenuta la presentazione del progetto che ci ha portati ad essere tutti l\u00ec nello stesso momento.&nbsp;<\/p>\n\n\n\n<p>Abbiamo svolto delle attivit\u00e0 per poterci conoscere meglio dato che eravamo in tanti ma si percepiva gi\u00e0 l\u2019inizio del legame che con il passare delle ore abbiamo stretto.&nbsp;<\/p>\n\n\n\n<p>In seguito abbiamo pranzato in mensa tutti insieme come il resto dei giorni, questo perch\u00e9 il cibo non ha solo una funzione puramente pratica, di sopravvivenza o di piacere, ma \u00e8 un momento di condivisione in cui si stringono i rapporti.&nbsp;<\/p>\n\n\n\n<p>Il pomeriggio \u00e8 stato dedicato alla visita del complesso di Valdocco in cui Don Bosco (1815-1888) port\u00f2 qui il suo primo Oratorio, vi fond\u00f2 i Salesiani e l\u00ec visse fino al giorno della morte avvenuta il 31\/1\/1888.&nbsp;<\/p>\n\n\n\n<p>Sorge nel quartiere di Borgo Dora ed \u00e8 considerato il cuore della Famiglia Salesiana e comprende attualmente la Basilica di Maria Ausiliatrice, la Chiesa di San Francesco di Sales, La Cappella Pinardi, gli edifici della scuola media e di quella professionale, la parrocchia e l\u2019oratorio.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"4679\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017-1024x768.jpg\" alt=\"\" class=\"wp-image-4679\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017-1024x768.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017-300x225.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017-768x576.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017-1536x1152.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0017.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large vk_block-margin-0--margin-top\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"4681\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-1024x577.jpg\" alt=\"\" class=\"wp-image-4681\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-1024x577.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-300x169.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-768x432.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-1536x865.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1-320x180.jpg 320w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0059-1.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"4678\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021-768x1024.jpg\" alt=\"\" class=\"wp-image-4678\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021-768x1024.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021-225x300.jpg 225w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021-1152x1536.jpg 1152w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260416-WA0021.jpg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p>SERATA&nbsp;<\/p>\n\n\n\n<p>Don Bosco trasforma il concetto di Oratorio: non \u00e8 solo un luogo di preghiera, ma una casa che accoglie, una scuola che istruisce e un cortile dove giocare.&nbsp;<\/p>\n\n\n\n<p>La sera ci siamo ritrovati nel cortile della scuola, in cui abbiamo vissuto un momento oratoriale caratterizzato da musica, giochi, risate e convivialit\u00e0.&nbsp;<\/p>\n\n\n\n<p>La sfida tra le squadre e la competitivit\u00e0 non hanno limitato il divertimento, anzi ci siamo sentiti tutti estremamente legati, quasi come se ci conoscessimo da anni.&nbsp;<\/p>\n\n\n\n<p>Per Don Bosco, il gioco non era una &#8220;pausa&#8221; dall&#8217;educazione o un semplice momento di ricreazione per far sfogare i ragazzi, era il centro del suo metodo. Egli diceva spesso che un oratorio senza musica e senza gioco \u00e8 come un &#8220;corpo senza anima&#8221;.&nbsp;<\/p>\n\n\n\n<p>Ogni battuta, risata, ogni punto guadagnato per la propria squadra e abbraccio hanno reso unica la serata vissuta.&nbsp;<\/p>\n\n\n\n<p>La &#8220;Buonanotte&#8221; di Don Bosco \u00e8 molto pi\u00f9 di un semplice saluto prima di dormire: \u00e8 una delle tradizioni pi\u00f9 intime e caratteristiche del sistema educativo salesiano ed \u00e8 breve ma comunque familiare, caratterizzata dall\u2019affetto.&nbsp;<\/p>\n\n\n\n<p>\u00c8 proprio cos\u00ec che si \u00e8 conclusa la nostra serata, con la buonanotte, che ci ha riuniti nel cortile dopo una serata piena di emozioni, in particolare di felicit\u00e0.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" data-id=\"4686\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-scaled.jpg\" alt=\"\" class=\"wp-image-4686\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-scaled.jpg 2560w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-300x200.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-1024x683.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-768x512.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-1536x1024.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0034-1-edited-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"2268\" height=\"1701\" data-id=\"4685\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited.jpg\" alt=\"\" class=\"wp-image-4685\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited.jpg 2268w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited-300x225.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited-1024x768.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited-768x576.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited-1536x1152.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/PXL_20260416_190948999.MP-1-edited-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 2268px) 100vw, 2268px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>17 aprile&nbsp;<\/strong><\/p>\n\n\n\n<p>La seconda, e ultima, tappa del nostro viaggio \u00e8 iniziata con un momento iniziale di preghiera, attraverso la messa di cui i canti sono stati selezionati da noi.&nbsp;<\/p>\n\n\n\n<p>In seguito a scuola abbiamo svolto un\u2019attivit\u00e0 sull\u2019importanza della partecipazione nella vita in cui attraverso una riflessione abbiamo individuato dei momenti in cui ci siamo sentiti realmente partecipi.&nbsp;<\/p>\n\n\n\n<p>Alla fine dell\u2019attivit\u00e0 abbiamo condiviso le nostre conclusioni e anche un momento di pausa, parlando e mangiando.&nbsp;<\/p>\n\n\n\n<p>Dopo il pranzo abbiamo visionato i video fatti da noi.&nbsp;<\/p>\n\n\n\n<p>Ogni scuola aveva il compito di intervistare i rappresentanti d\u2019istituto di alcune scuole salesiane del mondo.&nbsp;<\/p>\n\n\n\n<p>Ed \u00e8 proprio nel pomeriggio che abbiamo visto quei video, immergendoci in realt\u00e0 spesso diverse dalle nostre facendoci sentire lontani fisicamente da loro ma al contempo vicini perch\u00e9 condividiamo lo stesso concetto di scuola e di vita.&nbsp;<\/p>\n\n\n\n<p>Nel frattempo avevamo a disposizione un lungo cartellone su cui avevamo la piena libert\u00e0 di disegnare, scrivere e colorare seguendo le emozioni che provavamo durante i video:&nbsp;<\/p>\n\n\n\n<p>Alla fine di questa attivit\u00e0 a scuola abbiamo registrato altri video rispondendo alle stesse domande che avevamo posto noi e inoltre attraverso un brain-storming abbiamo condiviso le forti emozioni provate in questi giorni.&nbsp;<\/p>\n\n\n\n<p>La giornata \u00e8 proseguita con la cena, dunque ci siamo avviati verso la pizzeria a piedi in modo tale da vedere la citt\u00e0 di Torino lungo il tragitto&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" data-id=\"4688\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-1024x577.jpg\" alt=\"\" class=\"wp-image-4688\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-1024x577.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-300x169.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-768x432.jpg 768w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-1536x865.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2-320x180.jpg 320w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0041-2.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"1152\" data-id=\"4689\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1-edited.jpg\" alt=\"\" class=\"wp-image-4689\" srcset=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1-edited.jpg 1536w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1-edited-300x225.jpg 300w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1-edited-1024x768.jpg 1024w, https:\/\/istitutomariausiliatrice.it\/liceo\/files\/IMG-20260417-WA0045-1-edited-768x576.jpg 768w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<p class=\"has-text-align-center\"><strong>CONCLUSIONE&nbsp;<\/strong><\/p>\n\n\n\n<p>In conclusione, questo viaggio tanto atteso \u00e8 giunto al termine la sera del 17 aprile.&nbsp;<\/p>\n\n\n\n<p>Sono state inserite pi\u00f9 di venti persone in un contesto di socializzazione continua ed \u00e8 stata un\u2019esperienza importantissima per tutti noi.&nbsp;<\/p>\n\n\n\n<p>Siamo tutti diversi, con caratteri, abitudini, accenti, stili di vita e ambizioni proprie ma abbiamo trovato immediatamente la sintonia che ancora al giorno d\u2019oggi, passate settimane, ci lega.&nbsp;<\/p>\n\n\n\n<p>Ci siamo paragonati alla \u201cNotte stellata\u201d di Van Gogh, uno dei capolavori del pittore in cui ha inserito colori diversi in un modo particolare, che pu\u00f2 sembrare inizialmente casuale. Ecco, noi siamo quei colori, ci siamo ritrovati in una tela bianca che abbiamo riempito e alla fine abbiamo creato il nostro di capolavoro.&nbsp;<\/p>\n\n\n\n<p>Il viaggio a Torino si \u00e8 concluso ma ci auguriamo che l\u2019amicizia che ora ci lega non finisca mai.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Articolo di Maria Raluca Mustata<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>16- 17 aprile 2026,&nbsp; Torino&nbsp; INTRODUZIONE&nbsp; Il 16 e il 17 aprile si sono riuniti a Torino i rappresentanti d\u2019istituto delle scuole salesiane di tutta Italia.&nbsp; Il primo incontro \u00e8 avvenuto il 4 marzo, insieme agli studenti di tutte le scuole coinvolte.&nbsp; La ricorrenza di quel giorno era dedicata ai 150 anni di viaggio di [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4672,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"common","vkexunit_cta_each_option":"","_lightning_design_setting":{"layout":"default"},"footnotes":""},"categories":[105,80,25,11,12,78],"tags":[],"class_list":["post-4663","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-s-2025-26","category-evento","category-les-liceo-economico-sociale","category-liceo-delle-scienze-umane","category-liceo-linguistico","category-we-are-maux"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=4663"}],"version-history":[{"count":3,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4663\/revisions"}],"predecessor-version":[{"id":4690,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/4663\/revisions\/4690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media\/4672"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=4663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=4663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=4663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}