{"id":777,"date":"2012-11-14T23:38:45","date_gmt":"2012-11-14T22:38:45","guid":{"rendered":"http:\/\/www.istitutomariausiliatrice.it\/liceo\/?p=777"},"modified":"2013-12-30T10:51:50","modified_gmt":"2013-12-30T09:51:50","slug":"stage-orientativi-e-tempo-di-bilancio","status":"publish","type":"post","link":"https:\/\/istitutomariausiliatrice.it\/liceo\/2012\/11\/14\/stage-orientativi-e-tempo-di-bilancio\/","title":{"rendered":"Stage orientativi: \u00e8 tempo di bilancio"},"content":{"rendered":"<div><strong><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Schermata-2012-10-29-alle-00.33.45.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-778\" title=\"Schermata 2012-10-29 alle 00.33.45\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/Schermata-2012-10-29-alle-00.33.45.png\" alt=\"\" width=\"275\" height=\"231\" \/><\/a>Con il mese di settembre si sono conclusi gli stage orientativi cui hanno partecipato \u00a0alcuni nostri studenti delle classi quarte nell&#8217;ambito del progetto ScuoLav.<\/strong><\/div>\n<div><strong>Pubblichiamo un estratto delle relazioni conclusive di alcuni di essi.<\/strong><\/div>\n<div><\/div>\n<div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h4>ILARIA :\u00a0STUDIO LEGALE<\/h4>\n<p><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_ilaria5A.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-788\" title=\"stage_ilaria5A\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_ilaria5A.jpg\" alt=\"\" width=\"107\" height=\"164\" \/><\/a>Grazie alla possibilit\u00e0 che mi \u00e8 stata offerta dalla scuola, ho potuto partecipare ad uno stage\u00a0orientativo. La mia scelta \u00e8 caduta sullo studio di un avvocato penalista in quanto desideravo<br \/>\nmeglio conoscere il suo ruolo all&#8217; interno di un processo penale e per comprendere come si<br \/>\narticola la sua professione alla quale ambisco. Durante le tre settimane di stage ho avuto la<br \/>\npossibilit\u00e0 di frequentare il Tribunale e assistere a vari processi. Una delle attivit\u00e0 che ho svolto<br \/>\ncon particolare interesse \u00e8 stata quella di ricerca in studio, ossia la disamina di casi affiancata dal\u00a0professionista cercando di individuare con il suo aiuto le possibili strategie difensive.<br \/>\nHo avuto cos\u00ec modo di approfondire la mia conoscenza del codice penale, leggendolo ed<br \/>\nascoltandone le interpretazioni date dall\u2019avvocato.<\/p>\n<p>L\u2019esperienza vissuta che ho pi\u00f9 gradito \u00e8 stata per\u00f2 la partecipazione al processo di alcuni\u00a0imputati all&#8217;interno dell\u2019 aula bunker del carcere Le Vallette di Torino. Sono grata al mio tutor di\u00a0aver assecondato il mio specifico interesse per il fenomeno mafioso facendomi assistere a questo\u00a0processo.<\/p>\n<p>Consiglio vivamente ai ragazzi del liceo di vivere l\u2019esperienza dello stage, ottimo strumento<br \/>\nper comprendere meglio ci\u00f2 che \u00e8 realmente la professione e dunque scegliere con maggiore<br \/>\nconsapevolezza il proprio percorso di studi.<\/p>\n<h4><\/h4>\n<p>&nbsp;<\/p>\n<h4>CHIARA: AGENZIA ORGANIZZATRICE DI EVENTI<\/h4>\n<p><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_chiara5A.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-791 alignleft\" title=\"stage_chiara5A\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_chiara5A.jpg\" alt=\"\" width=\"110\" height=\"146\" \/><\/a>Quest&#8217;anno la nostra scuola ha accolto un&#8217;ottima iniziativa: dare la possibilit\u00e0 ad alcuni studenti<br \/>\ndi poter svolgere uno stage estivo in modo da approfondire al meglio cosa significhi realmente il\u00a0mondo del lavoro.<br \/>\nLa mia scelta \u00e8 caduta su di una societ\u00e0 che si occupa di organizzazione di eventi, essendo questa\u00a0una mia grande passione di cui spero in futuro di occuparmene.<br \/>\nIn particolare questa agenzia \u00e8 specializzata da molti anni nei settori della moda, della pubblicit\u00e0 e\u00a0dello spettacolo e organizza sfilate ed eventi per contodi aziende e privati.<br \/>\nQuesta agenzia \u00e8 gestita da tre responsabili, due generali e uno della contabilit\u00e0; per<br \/>\nloro lavorano altre tre persone che si occupano della gestione pratica del materiale<br \/>\nfotografico,video,organizzazione e casting per pubblicit\u00e0 o comparse.<br \/>\nLe persone con cui ho lavorato sono state molto cordiali e mi hanno sempre aiutato in caso di<br \/>\nnecessit\u00e0; il mio ruolo era sostanzialmente quello della gestione dell&#8217;archivio, l&#8217;inserimento di dati\u00a0personali degli iscritti all&#8217;agenzia quindi ho fatto molto uso del computer. Ogni tanto, per\u00f2, entravo\u00a0anche in contatto con i clienti fissando appuntamenti e svolgendo lavori di segreteria.<br \/>\nDa questa esperienza ho imparato a conoscere il mondo del lavoro nella sua quotidianit\u00e0, molto\u00a0diverso da quello scolastico; le mansioni che ho svolto hanno richiesto molto impegno ma sonocontenta del risultato ottenuto.<br \/>\nHo collaborato con persone squisite che mi hanno sempre fatto sentire a mio agio, aiutandomi nei\u00a0momenti di difficolt\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<h4>ANTONELLA: HOTEL RECEPTION<\/h4>\n<p><strong><\/strong><a href=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_antonella5A.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" title=\"stage_antonella5A\" src=\"https:\/\/istitutomariausiliatrice.it\/liceo\/files\/stage_antonella5A.jpg\" alt=\"\" width=\"134\" height=\"162\" \/><\/a>Nel mese\u00a0 di settembre ho svolto per tre settimane il mio stage presso un hotel della Best Western a Torino.<\/p>\n<p>Devo dire che i primi giorni ero molto ansiosa e preoccupata, questo forse anche dovuto dal fatto che mai prima di quel giorno avevo svolto il lavoro di receptionist in un albergo.<\/p>\n<p>Oggi a fine lavoro, posso affermare che tutto quello che ho fatto durante lo stage\u00a0 mi ha appassionato e in un certo senso mi ha positivamente riempito le giornate.<\/p>\n<p>Certo che il lavoro ha comportato\u00a0 sforzo e\u00a0 continua concentrazione, ma nonostante ci\u00f2 ripeterei l\u2019esperienza molto volentieri.<\/p>\n<p>Le persone con cui ho collaborato mi hanno tutte aiutato molto e non mi sono mai sentita esclusa.<\/p>\n<p>Le mie mansioni sono consistite nell\u2019 aiutare i clienti accogliendoli all\u2019arrivo in hotel, fornendo loro qualsiasi informazione avessero bisogno, registrando le loro prenotazioni. Dopo qualche giorno sono stata in grado di svolgere autonomamente i loro check-in e check-out.<\/p>\n<p>Ho avuto cos\u00ec modo di utilizzare le conoscenze delle lingue straniere apprese a scuola, in particolare l\u2019inglese.<\/p>\n<p>Desidero ringraziare tutte le persone che hanno collaborato e coordinato progetto SCUOLAV, in particolare le dott.se Sarah Giordano e Morena Mauro e \u00a0Maurizio Riva (tutor del progetto per il liceo) per un\u2019 iniziativa molto piacevole e soprattutto utile per noi giovani.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con il mese di settembre si sono conclusi gli stage orientativi cui hanno partecipato \u00a0alcuni nostri studenti delle classi quarte nell&#8217;ambito del progetto ScuoLav. Pubblichiamo un estratto delle relazioni conclusive di alcuni di essi. &nbsp; &nbsp; ILARIA :\u00a0STUDIO LEGALE Grazie alla possibilit\u00e0 che mi \u00e8 stata offerta dalla scuola, ho potuto partecipare ad uno stage\u00a0orientativo. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":793,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"sns_share_botton_hide":"","vkExUnit_sns_title":"","_vk_print_noindex":"","sitemap_hide":"","_veu_custom_css":"","veu_display_promotion_alert":"","vkexunit_cta_each_option":"","_lightning_design_setting":[],"footnotes":""},"categories":[25,10,11,13,39],"tags":[],"class_list":["post-777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-liceo-economico-sociale","category-liceo-della-comunicazione","category-liceo-delle-scienze-umane","category-nuovo-liceo-linguistico","category-stage-2"],"veu_head_title_object":{"title":"","add_site_title":""},"_links":{"self":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/comments?post=777"}],"version-history":[{"count":5,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/777\/revisions"}],"predecessor-version":[{"id":795,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/posts\/777\/revisions\/795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media\/793"}],"wp:attachment":[{"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/media?parent=777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/categories?post=777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/istitutomariausiliatrice.it\/liceo\/wp-json\/wp\/v2\/tags?post=777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}